{"id":13472,"date":"2020-08-04T19:56:36","date_gmt":"2020-08-04T23:56:36","guid":{"rendered":"https:\/\/inrs.ca\/professeurs\/professors\/mohamed-mohamedi\/"},"modified":"2022-07-23T07:22:59","modified_gmt":"2022-07-23T11:22:59","slug":"mohamed-mohamedi","status":"publish","type":"professor","link":"https:\/\/inrs.ca\/en\/research\/professors\/mohamed-mohamedi\/","title":{"rendered":"Mohamed Mohamedi"},"author":1,"featured_media":22995,"parent":13241,"template":"","sectors":[678,735,731],"expertise":[800,1034,1041],"taxo_thematic":[1964,1965,1969],"professor_program":[1195],"professor_education_offer":[],"expertise_groups":[1661,1670,1735,1720,1721,1747,1728,1717,1738,1745],"class_list":["post-13472","professor","type-professor","status-publish","has-post-thumbnail","hentry","sectors-biotechnologie-en","sectors-energie-en","sectors-materiaux-en","expertise-electrochemistry-and-micro-energy-systems","expertise-nanomaterials","expertise-nanostructures-en","taxo_thematic-biotechnologies-en","taxo_thematic-sustainable-energy-sources-and-applications","taxo_thematic-nanomaterials-and-advanced-manufacturing-processes","professor_program-energy-and-materials-science","expertise_groups-catalysis","expertise_groups-conversion-and-storage","expertise_groups-electrodes-en","expertise_groups-electronic-materials","expertise_groups-energetic-materials","expertise_groups-fuel-cells","expertise_groups-nanomaterials","expertise_groups-optical-materials","expertise_groups-ultrafast-optics","expertise_groups-ultrafast-photonics"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.1 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Mohamed Mohamedi | INRS<\/title>\n<meta name=\"description\" content=\"Int\u00e9r\u00eats de recherche Le professeur Mohamedi s\u2019int\u00e9resse aux microsyst\u00e8mes \u00e9nerg\u00e9tiques:D\u00e9veloppement de nouveaux concepts de piles \u00e0 combustible miniatures (&lt;0.02 cm2 micro-structur\u00e9es). Ce domaine fait appel aux technologies microsyst\u00e8mes \u00e9lectrom\u00e9caniques (MEMS) combin\u00e9es avec des m\u00e9thodes micro\/nano \u00e9lectrochimie. Ce type de piles s\u2019appliquent aux: micro-capteurs, MEMS sans fil, sources de micro-puissance pour appareils m\u00e9dicaux, etc. Les Micro-piles \u00e0 combustible passives (10~30 cm2) Air\/ Alcool. Ces piles utilisent l\u2019oxyg\u00e8ne contenu dans l\u2019air atmosph\u00e9rique, et la solution d\u2019alcool est stock\u00e9e dans un r\u00e9servoir incorpor\u00e9. Ce type de piles est destin\u00e9 pour l\u2019\u00e9lectronique portable: les ordinateurs portatifs, et les t\u00e9l\u00e9phones cellulaires.Micro\/nano fabrication \u00e9lectrochimique de nouveaux mat\u00e9riaux d\u2019\u00e9lectrode pour micro- batteries au lithium.D\u00e9veloppement de nouveaux mat\u00e9riaux superoxydes ou carbon\u00e9s pour les micro- supercapaciteurs.D\u00e9veloppement des m\u00e9thodes micro\u00e9lectroanalytiques avanc\u00e9es: \u00e9lectrode mono-particule, \u00e9lectrode \u00e0 microcavit\u00e9, ultramicro\u00e9lectrodes int\u00e9gr\u00e9es, \u00e9lectrodes \u00e0 micror\u00e9seaux interdigit\u00e9s.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/inrs.ca\/en\/research\/professors\/mohamed-mohamedi\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mohamed Mohamedi\" \/>\n<meta property=\"og:description\" content=\"Int\u00e9r\u00eats de recherche Le professeur Mohamedi s\u2019int\u00e9resse aux microsyst\u00e8mes \u00e9nerg\u00e9tiques:D\u00e9veloppement de nouveaux concepts de piles \u00e0 combustible miniatures (&lt;0.02 cm2 micro-structur\u00e9es). Ce domaine fait appel aux technologies microsyst\u00e8mes \u00e9lectrom\u00e9caniques (MEMS) combin\u00e9es avec des m\u00e9thodes micro\/nano \u00e9lectrochimie. Ce type de piles s\u2019appliquent aux: micro-capteurs, MEMS sans fil, sources de micro-puissance pour appareils m\u00e9dicaux, etc. Les Micro-piles \u00e0 combustible passives (10~30 cm2) Air\/ Alcool. Ces piles utilisent l\u2019oxyg\u00e8ne contenu dans l\u2019air atmosph\u00e9rique, et la solution d\u2019alcool est stock\u00e9e dans un r\u00e9servoir incorpor\u00e9. Ce type de piles est destin\u00e9 pour l\u2019\u00e9lectronique portable: les ordinateurs portatifs, et les t\u00e9l\u00e9phones cellulaires.Micro\/nano fabrication \u00e9lectrochimique de nouveaux mat\u00e9riaux d\u2019\u00e9lectrode pour micro- batteries au lithium.D\u00e9veloppement de nouveaux mat\u00e9riaux superoxydes ou carbon\u00e9s pour les micro- supercapaciteurs.D\u00e9veloppement des m\u00e9thodes micro\u00e9lectroanalytiques avanc\u00e9es: \u00e9lectrode mono-particule, \u00e9lectrode \u00e0 microcavit\u00e9, ultramicro\u00e9lectrodes int\u00e9gr\u00e9es, \u00e9lectrodes \u00e0 micror\u00e9seaux interdigit\u00e9s.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/inrs.ca\/en\/research\/professors\/mohamed-mohamedi\/\" \/>\n<meta property=\"og:site_name\" content=\"INRS\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/inrsciences\/\" \/>\n<meta property=\"article:modified_time\" content=\"2022-07-23T11:22:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/inrs.ca\/wp-content\/uploads\/2020\/04\/Mohamedi-Mohamed.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"708\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@inrsciences\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/inrs.ca\\\/en\\\/research\\\/professors\\\/mohamed-mohamedi\\\/\",\"url\":\"https:\\\/\\\/inrs.ca\\\/en\\\/research\\\/professors\\\/mohamed-mohamedi\\\/\",\"name\":\"Mohamed Mohamedi | INRS\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/inrs.ca\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/inrs.ca\\\/en\\\/research\\\/professors\\\/mohamed-mohamedi\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/inrs.ca\\\/en\\\/research\\\/professors\\\/mohamed-mohamedi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/inrs.ca\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/Mohamedi-Mohamed.jpg\",\"datePublished\":\"2020-08-04T23:56:36+00:00\",\"dateModified\":\"2022-07-23T11:22:59+00:00\",\"description\":\"Int\u00e9r\u00eats de recherche Le professeur Mohamedi s\u2019int\u00e9resse aux microsyst\u00e8mes \u00e9nerg\u00e9tiques:D\u00e9veloppement de nouveaux concepts de piles \u00e0 combustible miniatures (&lt;0.02 cm2 micro-structur\u00e9es). Ce domaine fait appel aux technologies microsyst\u00e8mes \u00e9lectrom\u00e9caniques (MEMS) combin\u00e9es avec des m\u00e9thodes micro\\\/nano \u00e9lectrochimie. Ce type de piles s\u2019appliquent aux: micro-capteurs, MEMS sans fil, sources de micro-puissance pour appareils m\u00e9dicaux, etc. Les Micro-piles \u00e0 combustible passives (10~30 cm2) Air\\\/ Alcool. Ces piles utilisent l\u2019oxyg\u00e8ne contenu dans l\u2019air atmosph\u00e9rique, et la solution d\u2019alcool est stock\u00e9e dans un r\u00e9servoir incorpor\u00e9. Ce type de piles est destin\u00e9 pour l\u2019\u00e9lectronique portable: les ordinateurs portatifs, et les t\u00e9l\u00e9phones cellulaires.Micro\\\/nano fabrication \u00e9lectrochimique de nouveaux mat\u00e9riaux d\u2019\u00e9lectrode pour micro- batteries au lithium.D\u00e9veloppement de nouveaux mat\u00e9riaux superoxydes ou carbon\u00e9s pour les micro- supercapaciteurs.D\u00e9veloppement des m\u00e9thodes micro\u00e9lectroanalytiques avanc\u00e9es: \u00e9lectrode mono-particule, \u00e9lectrode \u00e0 microcavit\u00e9, ultramicro\u00e9lectrodes int\u00e9gr\u00e9es, \u00e9lectrodes \u00e0 micror\u00e9seaux interdigit\u00e9s.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/inrs.ca\\\/en\\\/research\\\/professors\\\/mohamed-mohamedi\\\/#breadcrumb\"},\"inLanguage\":\"en-CA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/inrs.ca\\\/en\\\/research\\\/professors\\\/mohamed-mohamedi\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-CA\",\"@id\":\"https:\\\/\\\/inrs.ca\\\/en\\\/research\\\/professors\\\/mohamed-mohamedi\\\/#primaryimage\",\"url\":\"https:\\\/\\\/inrs.ca\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/Mohamedi-Mohamed.jpg\",\"contentUrl\":\"https:\\\/\\\/inrs.ca\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/Mohamedi-Mohamed.jpg\",\"width\":900,\"height\":708,\"caption\":\"Professeur INRS\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/inrs.ca\\\/en\\\/research\\\/professors\\\/mohamed-mohamedi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/inrs.ca\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Research\",\"item\":\"https:\\\/\\\/inrs.ca\\\/en\\\/research\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Professors\",\"item\":\"https:\\\/\\\/inrs.ca\\\/en\\\/research\\\/professors\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Mohamed Mohamedi\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/inrs.ca\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/inrs.ca\\\/en\\\/\",\"name\":\"INRS\",\"description\":\"Institut national de la recherche scientifique\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/inrs.ca\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-CA\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Mohamed Mohamedi | INRS","description":"Int\u00e9r\u00eats de recherche Le professeur Mohamedi s\u2019int\u00e9resse aux microsyst\u00e8mes \u00e9nerg\u00e9tiques:D\u00e9veloppement de nouveaux concepts de piles \u00e0 combustible miniatures (&lt;0.02 cm2 micro-structur\u00e9es). Ce domaine fait appel aux technologies microsyst\u00e8mes \u00e9lectrom\u00e9caniques (MEMS) combin\u00e9es avec des m\u00e9thodes micro\/nano \u00e9lectrochimie. Ce type de piles s\u2019appliquent aux: micro-capteurs, MEMS sans fil, sources de micro-puissance pour appareils m\u00e9dicaux, etc. Les Micro-piles \u00e0 combustible passives (10~30 cm2) Air\/ Alcool. Ces piles utilisent l\u2019oxyg\u00e8ne contenu dans l\u2019air atmosph\u00e9rique, et la solution d\u2019alcool est stock\u00e9e dans un r\u00e9servoir incorpor\u00e9. Ce type de piles est destin\u00e9 pour l\u2019\u00e9lectronique portable: les ordinateurs portatifs, et les t\u00e9l\u00e9phones cellulaires.Micro\/nano fabrication \u00e9lectrochimique de nouveaux mat\u00e9riaux d\u2019\u00e9lectrode pour micro- batteries au lithium.D\u00e9veloppement de nouveaux mat\u00e9riaux superoxydes ou carbon\u00e9s pour les micro- supercapaciteurs.D\u00e9veloppement des m\u00e9thodes micro\u00e9lectroanalytiques avanc\u00e9es: \u00e9lectrode mono-particule, \u00e9lectrode \u00e0 microcavit\u00e9, ultramicro\u00e9lectrodes int\u00e9gr\u00e9es, \u00e9lectrodes \u00e0 micror\u00e9seaux interdigit\u00e9s.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/inrs.ca\/en\/research\/professors\/mohamed-mohamedi\/","og_locale":"en_US","og_type":"article","og_title":"Mohamed Mohamedi","og_description":"Int\u00e9r\u00eats de recherche Le professeur Mohamedi s\u2019int\u00e9resse aux microsyst\u00e8mes \u00e9nerg\u00e9tiques:D\u00e9veloppement de nouveaux concepts de piles \u00e0 combustible miniatures (&lt;0.02 cm2 micro-structur\u00e9es). Ce domaine fait appel aux technologies microsyst\u00e8mes \u00e9lectrom\u00e9caniques (MEMS) combin\u00e9es avec des m\u00e9thodes micro\/nano \u00e9lectrochimie. Ce type de piles s\u2019appliquent aux: micro-capteurs, MEMS sans fil, sources de micro-puissance pour appareils m\u00e9dicaux, etc. Les Micro-piles \u00e0 combustible passives (10~30 cm2) Air\/ Alcool. Ces piles utilisent l\u2019oxyg\u00e8ne contenu dans l\u2019air atmosph\u00e9rique, et la solution d\u2019alcool est stock\u00e9e dans un r\u00e9servoir incorpor\u00e9. Ce type de piles est destin\u00e9 pour l\u2019\u00e9lectronique portable: les ordinateurs portatifs, et les t\u00e9l\u00e9phones cellulaires.Micro\/nano fabrication \u00e9lectrochimique de nouveaux mat\u00e9riaux d\u2019\u00e9lectrode pour micro- batteries au lithium.D\u00e9veloppement de nouveaux mat\u00e9riaux superoxydes ou carbon\u00e9s pour les micro- supercapaciteurs.D\u00e9veloppement des m\u00e9thodes micro\u00e9lectroanalytiques avanc\u00e9es: \u00e9lectrode mono-particule, \u00e9lectrode \u00e0 microcavit\u00e9, ultramicro\u00e9lectrodes int\u00e9gr\u00e9es, \u00e9lectrodes \u00e0 micror\u00e9seaux interdigit\u00e9s.","og_url":"https:\/\/inrs.ca\/en\/research\/professors\/mohamed-mohamedi\/","og_site_name":"INRS","article_publisher":"https:\/\/www.facebook.com\/inrsciences\/","article_modified_time":"2022-07-23T11:22:59+00:00","og_image":[{"width":900,"height":708,"url":"https:\/\/inrs.ca\/wp-content\/uploads\/2020\/04\/Mohamedi-Mohamed.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@inrsciences","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/inrs.ca\/en\/research\/professors\/mohamed-mohamedi\/","url":"https:\/\/inrs.ca\/en\/research\/professors\/mohamed-mohamedi\/","name":"Mohamed Mohamedi | INRS","isPartOf":{"@id":"https:\/\/inrs.ca\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/inrs.ca\/en\/research\/professors\/mohamed-mohamedi\/#primaryimage"},"image":{"@id":"https:\/\/inrs.ca\/en\/research\/professors\/mohamed-mohamedi\/#primaryimage"},"thumbnailUrl":"https:\/\/inrs.ca\/wp-content\/uploads\/2020\/04\/Mohamedi-Mohamed.jpg","datePublished":"2020-08-04T23:56:36+00:00","dateModified":"2022-07-23T11:22:59+00:00","description":"Int\u00e9r\u00eats de recherche Le professeur Mohamedi s\u2019int\u00e9resse aux microsyst\u00e8mes \u00e9nerg\u00e9tiques:D\u00e9veloppement de nouveaux concepts de piles \u00e0 combustible miniatures (&lt;0.02 cm2 micro-structur\u00e9es). Ce domaine fait appel aux technologies microsyst\u00e8mes \u00e9lectrom\u00e9caniques (MEMS) combin\u00e9es avec des m\u00e9thodes micro\/nano \u00e9lectrochimie. Ce type de piles s\u2019appliquent aux: micro-capteurs, MEMS sans fil, sources de micro-puissance pour appareils m\u00e9dicaux, etc. Les Micro-piles \u00e0 combustible passives (10~30 cm2) Air\/ Alcool. Ces piles utilisent l\u2019oxyg\u00e8ne contenu dans l\u2019air atmosph\u00e9rique, et la solution d\u2019alcool est stock\u00e9e dans un r\u00e9servoir incorpor\u00e9. Ce type de piles est destin\u00e9 pour l\u2019\u00e9lectronique portable: les ordinateurs portatifs, et les t\u00e9l\u00e9phones cellulaires.Micro\/nano fabrication \u00e9lectrochimique de nouveaux mat\u00e9riaux d\u2019\u00e9lectrode pour micro- batteries au lithium.D\u00e9veloppement de nouveaux mat\u00e9riaux superoxydes ou carbon\u00e9s pour les micro- supercapaciteurs.D\u00e9veloppement des m\u00e9thodes micro\u00e9lectroanalytiques avanc\u00e9es: \u00e9lectrode mono-particule, \u00e9lectrode \u00e0 microcavit\u00e9, ultramicro\u00e9lectrodes int\u00e9gr\u00e9es, \u00e9lectrodes \u00e0 micror\u00e9seaux interdigit\u00e9s.","breadcrumb":{"@id":"https:\/\/inrs.ca\/en\/research\/professors\/mohamed-mohamedi\/#breadcrumb"},"inLanguage":"en-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/inrs.ca\/en\/research\/professors\/mohamed-mohamedi\/"]}]},{"@type":"ImageObject","inLanguage":"en-CA","@id":"https:\/\/inrs.ca\/en\/research\/professors\/mohamed-mohamedi\/#primaryimage","url":"https:\/\/inrs.ca\/wp-content\/uploads\/2020\/04\/Mohamedi-Mohamed.jpg","contentUrl":"https:\/\/inrs.ca\/wp-content\/uploads\/2020\/04\/Mohamedi-Mohamed.jpg","width":900,"height":708,"caption":"Professeur INRS"},{"@type":"BreadcrumbList","@id":"https:\/\/inrs.ca\/en\/research\/professors\/mohamed-mohamedi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/inrs.ca\/en\/"},{"@type":"ListItem","position":2,"name":"Research","item":"https:\/\/inrs.ca\/en\/research\/"},{"@type":"ListItem","position":3,"name":"Professors","item":"https:\/\/inrs.ca\/en\/research\/professors\/"},{"@type":"ListItem","position":4,"name":"Mohamed Mohamedi"}]},{"@type":"WebSite","@id":"https:\/\/inrs.ca\/en\/#website","url":"https:\/\/inrs.ca\/en\/","name":"INRS","description":"Institut national de la recherche scientifique","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/inrs.ca\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-CA"}]}},"permalink_manager":null,"_links":{"self":[{"href":"https:\/\/inrs.ca\/en\/wp-json\/wp\/v2\/professor\/13472","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/inrs.ca\/en\/wp-json\/wp\/v2\/professor"}],"about":[{"href":"https:\/\/inrs.ca\/en\/wp-json\/wp\/v2\/types\/professor"}],"author":[{"embeddable":true,"href":"https:\/\/inrs.ca\/en\/wp-json\/wp\/v2\/users\/1"}],"up":[{"embeddable":true,"href":"https:\/\/inrs.ca\/en\/wp-json\/wp\/v2\/pages\/13241"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/inrs.ca\/en\/wp-json\/wp\/v2\/media\/22995"}],"wp:attachment":[{"href":"https:\/\/inrs.ca\/en\/wp-json\/wp\/v2\/media?parent=13472"}],"wp:term":[{"taxonomy":"sectors","embeddable":true,"href":"https:\/\/inrs.ca\/en\/wp-json\/wp\/v2\/sectors?post=13472"},{"taxonomy":"expertise","embeddable":true,"href":"https:\/\/inrs.ca\/en\/wp-json\/wp\/v2\/expertise?post=13472"},{"taxonomy":"taxo_thematic","embeddable":true,"href":"https:\/\/inrs.ca\/en\/wp-json\/wp\/v2\/taxo_thematic?post=13472"},{"taxonomy":"professor_program","embeddable":true,"href":"https:\/\/inrs.ca\/en\/wp-json\/wp\/v2\/professor_program?post=13472"},{"taxonomy":"professor_education_offer","embeddable":true,"href":"https:\/\/inrs.ca\/en\/wp-json\/wp\/v2\/professor_education_offer?post=13472"},{"taxonomy":"expertise_groups","embeddable":true,"href":"https:\/\/inrs.ca\/en\/wp-json\/wp\/v2\/expertise_groups?post=13472"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}